{"id":8889,"date":"2024-11-18T19:07:51","date_gmt":"2024-11-18T18:07:51","guid":{"rendered":"https:\/\/zeroco2.eco\/?p=8889"},"modified":"2024-11-20T21:44:44","modified_gmt":"2024-11-20T20:44:44","slug":"cosa-e-science-based-targets-initiative","status":"publish","type":"post","link":"https:\/\/zeroco2.eco\/it\/magazine\/sostenibilita-aziendale\/cosa-e-science-based-targets-initiative\/","title":{"rendered":"Science Based Targets Initiative: la via delle aziende per il Net Zero"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":8910,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[28],"tags":[],"class_list":["post-8889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sostenibilita-aziendale","entry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SBTI: cos&#039;\u00e8 la Science Based Targets Initiative per aziende<\/title>\n<meta name=\"description\" content=\"Cos&#039;\u00e8 la Science Based Targets Initiative e qual \u00e8 il suo ruolo nel guidare le strategie scientifiche per aziende che puntano al Net Zero.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zeroco2.eco\/it\/magazine\/sostenibilita-aziendale\/cosa-e-science-based-targets-initiative\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SBTI: cos&#039;\u00e8 la Science Based Targets Initiative per aziende\" \/>\n<meta property=\"og:description\" content=\"Cos&#039;\u00e8 la Science Based Targets Initiative e qual \u00e8 il suo ruolo nel guidare le strategie scientifiche per aziende che puntano al Net Zero.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zeroco2.eco\/it\/magazine\/sostenibilita-aziendale\/cosa-e-science-based-targets-initiative\/\" \/>\n<meta property=\"og:site_name\" content=\"zeroCO2\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-18T18:07:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-20T20:44:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zeroco2.eco\/wp-content\/uploads\/2024\/11\/Comunita-Chile-Verde-Guatemala-zeroCO2-2.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"info@zeroco2.eco\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"info@zeroco2.eco\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/zeroco2.eco\\\/it\\\/magazine\\\/sostenibilita-aziendale\\\/cosa-e-science-based-targets-initiative\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zeroco2.eco\\\/it\\\/magazine\\\/sostenibilita-aziendale\\\/cosa-e-science-based-targets-initiative\\\/\"},\"author\":{\"name\":\"info@zeroco2.eco\",\"@id\":\"https:\\\/\\\/zeroco2.eco\\\/it\\\/#\\\/schema\\\/person\\\/6f27c207a18ff97393b578d65744c31c\"},\"headline\":\"Science Based Targets Initiative: la via delle aziende per il Net Zero\",\"datePublished\":\"2024-11-18T18:07:51+00:00\",\"dateModified\":\"2024-11-20T20:44:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/zeroco2.eco\\\/it\\\/magazine\\\/sostenibilita-aziendale\\\/cosa-e-science-based-targets-initiative\\\/\"},\"wordCount\":12,\"image\":{\"@id\":\"https:\\\/\\\/zeroco2.eco\\\/it\\\/magazine\\\/sostenibilita-aziendale\\\/cosa-e-science-based-targets-initiative\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zeroco2.eco\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Comunita-Chile-Verde-Guatemala-zeroCO2-2.webp\",\"articleSection\":[\"Sostenibilit\u00e0 aziendale\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zeroco2.eco\\\/it\\\/magazine\\\/sostenibilita-aziendale\\\/cosa-e-science-based-targets-initiative\\\/\",\"url\":\"https:\\\/\\\/zeroco2.eco\\\/it\\\/magazine\\\/sostenibilita-aziendale\\\/cosa-e-science-based-targets-initiative\\\/\",\"name\":\"SBTI: cos'\u00e8 la Science Based Targets Initiative per aziende\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zeroco2.eco\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zeroco2.eco\\\/it\\\/magazine\\\/sostenibilita-aziendale\\\/cosa-e-science-based-targets-initiative\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zeroco2.eco\\\/it\\\/magazine\\\/sostenibilita-aziendale\\\/cosa-e-science-based-targets-initiative\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zeroco2.eco\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Comunita-Chile-Verde-Guatemala-zeroCO2-2.webp\",\"datePublished\":\"2024-11-18T18:07:51+00:00\",\"dateModified\":\"2024-11-20T20:44:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/zeroco2.eco\\\/it\\\/#\\\/schema\\\/person\\\/6f27c207a18ff97393b578d65744c31c\"},\"description\":\"Cos'\u00e8 la Science Based Targets Initiative e qual \u00e8 il suo ruolo nel guidare le strategie scientifiche per aziende che puntano al Net Zero.\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zeroco2.eco\\\/it\\\/magazine\\\/sostenibilita-aziendale\\\/cosa-e-science-based-targets-initiative\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/zeroco2.eco\\\/it\\\/magazine\\\/sostenibilita-aziendale\\\/cosa-e-science-based-targets-initiative\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zeroco2.eco\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Comunita-Chile-Verde-Guatemala-zeroCO2-2.webp\",\"contentUrl\":\"https:\\\/\\\/zeroco2.eco\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Comunita-Chile-Verde-Guatemala-zeroCO2-2.webp\",\"width\":2000,\"height\":1335,\"caption\":\"Progetti di riforestazione in Guatemala - Chile Verde zeroCO2\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zeroco2.eco\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/zeroco2.eco\\\/it\\\/\",\"name\":\"zeroCO2\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zeroco2.eco\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/zeroco2.eco\\\/it\\\/#\\\/schema\\\/person\\\/6f27c207a18ff97393b578d65744c31c\",\"name\":\"info@zeroco2.eco\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SBTI: cos'\u00e8 la Science Based Targets Initiative per aziende","description":"Cos'\u00e8 la Science Based Targets Initiative e qual \u00e8 il suo ruolo nel guidare le strategie scientifiche per aziende che puntano al Net Zero.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zeroco2.eco\/it\/magazine\/sostenibilita-aziendale\/cosa-e-science-based-targets-initiative\/","og_locale":"it_IT","og_type":"article","og_title":"SBTI: cos'\u00e8 la Science Based Targets Initiative per aziende","og_description":"Cos'\u00e8 la Science Based Targets Initiative e qual \u00e8 il suo ruolo nel guidare le strategie scientifiche per aziende che puntano al Net Zero.","og_url":"https:\/\/zeroco2.eco\/it\/magazine\/sostenibilita-aziendale\/cosa-e-science-based-targets-initiative\/","og_site_name":"zeroCO2","article_published_time":"2024-11-18T18:07:51+00:00","article_modified_time":"2024-11-20T20:44:44+00:00","og_image":[{"width":2000,"height":1335,"url":"https:\/\/zeroco2.eco\/wp-content\/uploads\/2024\/11\/Comunita-Chile-Verde-Guatemala-zeroCO2-2.webp","type":"image\/webp"}],"author":"info@zeroco2.eco","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"info@zeroco2.eco","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/zeroco2.eco\/it\/magazine\/sostenibilita-aziendale\/cosa-e-science-based-targets-initiative\/#article","isPartOf":{"@id":"https:\/\/zeroco2.eco\/it\/magazine\/sostenibilita-aziendale\/cosa-e-science-based-targets-initiative\/"},"author":{"name":"info@zeroco2.eco","@id":"https:\/\/zeroco2.eco\/it\/#\/schema\/person\/6f27c207a18ff97393b578d65744c31c"},"headline":"Science Based Targets Initiative: la via delle aziende per il Net Zero","datePublished":"2024-11-18T18:07:51+00:00","dateModified":"2024-11-20T20:44:44+00:00","mainEntityOfPage":{"@id":"https:\/\/zeroco2.eco\/it\/magazine\/sostenibilita-aziendale\/cosa-e-science-based-targets-initiative\/"},"wordCount":12,"image":{"@id":"https:\/\/zeroco2.eco\/it\/magazine\/sostenibilita-aziendale\/cosa-e-science-based-targets-initiative\/#primaryimage"},"thumbnailUrl":"https:\/\/zeroco2.eco\/wp-content\/uploads\/2024\/11\/Comunita-Chile-Verde-Guatemala-zeroCO2-2.webp","articleSection":["Sostenibilit\u00e0 aziendale"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/zeroco2.eco\/it\/magazine\/sostenibilita-aziendale\/cosa-e-science-based-targets-initiative\/","url":"https:\/\/zeroco2.eco\/it\/magazine\/sostenibilita-aziendale\/cosa-e-science-based-targets-initiative\/","name":"SBTI: cos'\u00e8 la Science Based Targets Initiative per aziende","isPartOf":{"@id":"https:\/\/zeroco2.eco\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zeroco2.eco\/it\/magazine\/sostenibilita-aziendale\/cosa-e-science-based-targets-initiative\/#primaryimage"},"image":{"@id":"https:\/\/zeroco2.eco\/it\/magazine\/sostenibilita-aziendale\/cosa-e-science-based-targets-initiative\/#primaryimage"},"thumbnailUrl":"https:\/\/zeroco2.eco\/wp-content\/uploads\/2024\/11\/Comunita-Chile-Verde-Guatemala-zeroCO2-2.webp","datePublished":"2024-11-18T18:07:51+00:00","dateModified":"2024-11-20T20:44:44+00:00","author":{"@id":"https:\/\/zeroco2.eco\/it\/#\/schema\/person\/6f27c207a18ff97393b578d65744c31c"},"description":"Cos'\u00e8 la Science Based Targets Initiative e qual \u00e8 il suo ruolo nel guidare le strategie scientifiche per aziende che puntano al Net Zero.","inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zeroco2.eco\/it\/magazine\/sostenibilita-aziendale\/cosa-e-science-based-targets-initiative\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/zeroco2.eco\/it\/magazine\/sostenibilita-aziendale\/cosa-e-science-based-targets-initiative\/#primaryimage","url":"https:\/\/zeroco2.eco\/wp-content\/uploads\/2024\/11\/Comunita-Chile-Verde-Guatemala-zeroCO2-2.webp","contentUrl":"https:\/\/zeroco2.eco\/wp-content\/uploads\/2024\/11\/Comunita-Chile-Verde-Guatemala-zeroCO2-2.webp","width":2000,"height":1335,"caption":"Progetti di riforestazione in Guatemala - Chile Verde zeroCO2"},{"@type":"WebSite","@id":"https:\/\/zeroco2.eco\/it\/#website","url":"https:\/\/zeroco2.eco\/it\/","name":"zeroCO2","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zeroco2.eco\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/zeroco2.eco\/it\/#\/schema\/person\/6f27c207a18ff97393b578d65744c31c","name":"info@zeroco2.eco"}]}},"_links":{"self":[{"href":"https:\/\/zeroco2.eco\/it\/wp-json\/wp\/v2\/posts\/8889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zeroco2.eco\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zeroco2.eco\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zeroco2.eco\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/zeroco2.eco\/it\/wp-json\/wp\/v2\/comments?post=8889"}],"version-history":[{"count":17,"href":"https:\/\/zeroco2.eco\/it\/wp-json\/wp\/v2\/posts\/8889\/revisions"}],"predecessor-version":[{"id":8933,"href":"https:\/\/zeroco2.eco\/it\/wp-json\/wp\/v2\/posts\/8889\/revisions\/8933"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zeroco2.eco\/it\/wp-json\/wp\/v2\/media\/8910"}],"wp:attachment":[{"href":"https:\/\/zeroco2.eco\/it\/wp-json\/wp\/v2\/media?parent=8889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zeroco2.eco\/it\/wp-json\/wp\/v2\/categories?post=8889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zeroco2.eco\/it\/wp-json\/wp\/v2\/tags?post=8889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}